{"id":85560,"name":"Vasanth Madhure, Couchbase CISO","url":"","description":"","link":"https:\/\/www.couchbase.com\/blog\/es\/author\/vasanthmadhure\/","slug":"vasanthmadhure","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6f70a50b1d27c7d12dca6aaecddc86f6ab7c32c549dcc5aebcddeb7c5e2c21bb?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6f70a50b1d27c7d12dca6aaecddc86f6ab7c32c549dcc5aebcddeb7c5e2c21bb?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6f70a50b1d27c7d12dca6aaecddc86f6ab7c32c549dcc5aebcddeb7c5e2c21bb?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vasanth Madhure, Couchbase CISO, Author at The Couchbase Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.couchbase.com\/blog\/es\/author\/vasanthmadhure\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Vasanth Madhure, Couchbase CISO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.couchbase.com\/blog\/es\/author\/vasanthmadhure\/\" \/>\n<meta property=\"og:site_name\" content=\"The Couchbase Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.couchbase.com\/blog\/wp-content\/uploads\/sites\/5\/2026\/05\/vasanthmadhure_couchbase_ciso-1.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/author\\\/vasanthmadhure\\\/\",\"url\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/author\\\/vasanthmadhure\\\/\",\"name\":\"Vasanth Madhure, Couchbase CISO, Author at The Couchbase Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/author\\\/vasanthmadhure\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/author\\\/vasanthmadhure\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/author\\\/vasanthmadhure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Vasanth Madhure, Couchbase CISO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/\",\"name\":\"The Couchbase Blog\",\"description\":\"Couchbase, the NoSQL Database\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/#organization\",\"name\":\"The Couchbase Blog\",\"url\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"The Couchbase Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/#\\\/schema\\\/person\\\/cc9d5d456fcf1fccf21b68f87881ae84\",\"name\":\"Vasanth Madhure, Couchbase CISO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f70a50b1d27c7d12dca6aaecddc86f6ab7c32c549dcc5aebcddeb7c5e2c21bb?s=96&d=mm&r=g07554f7f8de8e578313f7e5ebc0ed6eb\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f70a50b1d27c7d12dca6aaecddc86f6ab7c32c549dcc5aebcddeb7c5e2c21bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f70a50b1d27c7d12dca6aaecddc86f6ab7c32c549dcc5aebcddeb7c5e2c21bb?s=96&d=mm&r=g\",\"caption\":\"Vasanth Madhure, Couchbase CISO\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.couchbase.com\\\/blog\\\/author\\\/vasanthmadhure\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vasanth Madhure, Couchbase CISO, Author at The Couchbase Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.couchbase.com\/blog\/es\/author\/vasanthmadhure\/","og_locale":"es_MX","og_type":"profile","og_title":"Vasanth Madhure, Couchbase CISO","og_url":"https:\/\/www.couchbase.com\/blog\/es\/author\/vasanthmadhure\/","og_site_name":"The Couchbase Blog","og_image":[{"url":"https:\/\/www.couchbase.com\/blog\/wp-content\/uploads\/sites\/5\/2026\/05\/vasanthmadhure_couchbase_ciso-1.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/www.couchbase.com\/blog\/author\/vasanthmadhure\/","url":"https:\/\/www.couchbase.com\/blog\/author\/vasanthmadhure\/","name":"Vasanth Madhure, Couchbase CISO, Author at The Couchbase Blog","isPartOf":{"@id":"https:\/\/www.couchbase.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.couchbase.com\/blog\/author\/vasanthmadhure\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.couchbase.com\/blog\/author\/vasanthmadhure\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.couchbase.com\/blog\/author\/vasanthmadhure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.couchbase.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Archives for Vasanth Madhure, Couchbase CISO"}]},{"@type":"WebSite","@id":"https:\/\/www.couchbase.com\/blog\/#website","url":"https:\/\/www.couchbase.com\/blog\/","name":"The Couchbase Blog","description":"Couchbase, the NoSQL Database","publisher":{"@id":"https:\/\/www.couchbase.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.couchbase.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.couchbase.com\/blog\/#organization","name":"The Couchbase Blog","url":"https:\/\/www.couchbase.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.couchbase.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.couchbase.com\/blog\/wp-content\/uploads\/sites\/5\/2026\/06\/logo.svg","contentUrl":"https:\/\/www.couchbase.com\/blog\/wp-content\/uploads\/sites\/5\/2026\/06\/logo.svg","width":"1024","height":"1024","caption":"The Couchbase Blog"},"image":{"@id":"https:\/\/www.couchbase.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.couchbase.com\/blog\/#\/schema\/person\/cc9d5d456fcf1fccf21b68f87881ae84","name":"Vasanth Madhure, Couchbase CISO","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6f70a50b1d27c7d12dca6aaecddc86f6ab7c32c549dcc5aebcddeb7c5e2c21bb?s=96&d=mm&r=g07554f7f8de8e578313f7e5ebc0ed6eb","url":"https:\/\/secure.gravatar.com\/avatar\/6f70a50b1d27c7d12dca6aaecddc86f6ab7c32c549dcc5aebcddeb7c5e2c21bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f70a50b1d27c7d12dca6aaecddc86f6ab7c32c549dcc5aebcddeb7c5e2c21bb?s=96&d=mm&r=g","caption":"Vasanth Madhure, Couchbase CISO"},"mainEntityOfPage":{"@id":"https:\/\/www.couchbase.com\/blog\/author\/vasanthmadhure\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.couchbase.com\/blog\/es\/wp-json\/wp\/v2\/users\/85560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.couchbase.com\/blog\/es\/wp-json\/wp\/v2\/users"}]}}